{"id":25658,"date":"2022-05-18T12:49:49","date_gmt":"2022-05-18T10:49:49","guid":{"rendered":"http:\/\/timple.nl\/product\/spksb45-w-wasserdichte-sound-bar\/"},"modified":"2022-09-29T11:55:01","modified_gmt":"2022-09-29T09:55:01","slug":"spksb45-w","status":"publish","type":"product","link":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/","title":{"rendered":"<b>SPKSB45-W<\/b> <br>Wasserdichten Sound-Bar"},"content":{"rendered":"<p>Ihr iPhone oder SmartPhone als Quelle f\u00fcr den wasserdichten Sound-Bar. Die Musik wird \u00fcber Bluetooth an diesen Sound-Bar gesendet. Der Bluetooth Sound-Bar ist wasserdicht (IPX5), so dass er ideal f\u00fcr den Einsatz im Badezimmer ist. Mit dem mitgelieferten St\u00e4nder kann der Sound-Bar auf 4 verschiedene Arten positioniert werden. Sowohl stehend als auch an der Wand montiert. Horizontal und vertikal. Nur 3 Tasten sorgen f\u00fcr eine beispiellose Benutzerfreundlichkeit.<\/p>\n<ul>\n<li>Ein \/ Aus<\/li>\n<li>V+ \/ V-<\/li>\n<li>Spur+ \/ Spur-<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>Technische Daten<\/h4>\n<ul>\n<li>470 x 80 x 70 mm<\/li>\n<li>25 Watt<\/li>\n<li>AUX-Anschluss (Mini-Klinke)<\/li>\n<li>Bluetooth 4.0<\/li>\n<li>IPX5 Zertifizierung<\/li>\n<li>Standfu\u00df f\u00fcr Bodenmontage (horizontal und vertikal)<\/li>\n<li>Sockel f\u00fcr die Wandmontage (horizontal und vertikal)<\/li>\n<li>230 V \/ 12 V (Adapter)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ihr iPhone oder SmartPhone als Quelle f\u00fcr den wasserdichten Sound-Bar. Die Musik wird \u00fcber Bluetooth an diesen Sound-Bar gesendet. Der Bluetooth Sound-Bar ist wasserdicht (IPX5), so dass er ideal f\u00fcr den Einsatz im Badezimmer ist. Mit dem mitgelieferten St\u00e4nder kann der Sound-Bar auf 4 verschiedene Arten positioniert werden. Sowohl stehend als auch an der Wand [&hellip;]<\/p>\n","protected":false},"featured_media":24800,"template":"","meta":[],"product_brand":[],"product_cat":[67,68],"product_tag":[],"class_list":{"0":"post-25658","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-badezimmer-lautsprecher","7":"product_cat-bluetooth-audiosysteme","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SPKSB45-W Wasserdichten Sound-Bar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPKSB45-W Wasserdichten Sound-Bar\" \/>\n<meta property=\"og:description\" content=\"Ihr iPhone oder SmartPhone als Quelle f\u00fcr den wasserdichten Sound-Bar. Die Musik wird \u00fcber Bluetooth an diesen Sound-Bar gesendet. Der Bluetooth Sound-Bar ist wasserdicht (IPX5), so dass er ideal f\u00fcr den Einsatz im Badezimmer ist. Mit dem mitgelieferten St\u00e4nder kann der Sound-Bar auf 4 verschiedene Arten positioniert werden. Sowohl stehend als auch an der Wand [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/\" \/>\n<meta property=\"og:site_name\" content=\"AquaSound\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-29T09:55:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aquasound.eu\/wp-content\/uploads\/SPKSB45-W-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aquasound.eu\\\/de\\\/produkt\\\/spksb45-w\\\/\",\"url\":\"https:\\\/\\\/aquasound.eu\\\/de\\\/produkt\\\/spksb45-w\\\/\",\"name\":\"SPKSB45-W Wasserdichten Sound-Bar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aquasound.eu\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aquasound.eu\\\/de\\\/produkt\\\/spksb45-w\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aquasound.eu\\\/de\\\/produkt\\\/spksb45-w\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aquasound.eu\\\/wp-content\\\/uploads\\\/SPKSB45-W-2.webp\",\"datePublished\":\"2022-05-18T10:49:49+00:00\",\"dateModified\":\"2022-09-29T09:55:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aquasound.eu\\\/de\\\/produkt\\\/spksb45-w\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aquasound.eu\\\/de\\\/produkt\\\/spksb45-w\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aquasound.eu\\\/de\\\/produkt\\\/spksb45-w\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aquasound.eu\\\/wp-content\\\/uploads\\\/SPKSB45-W-2.webp\",\"contentUrl\":\"https:\\\/\\\/aquasound.eu\\\/wp-content\\\/uploads\\\/SPKSB45-W-2.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aquasound.eu\\\/de\\\/produkt\\\/spksb45-w\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aquasound.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WooCommerce\",\"item\":\"https:\\\/\\\/aquasound.eu\\\/nl\\\/woocommerce\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SPKSB45-W Wasserdichten Sound-Bar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aquasound.eu\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/aquasound.eu\\\/nl\\\/\",\"name\":\"AquaSound\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aquasound.eu\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SPKSB45-W Wasserdichten Sound-Bar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/","og_locale":"de_DE","og_type":"article","og_title":"SPKSB45-W Wasserdichten Sound-Bar","og_description":"Ihr iPhone oder SmartPhone als Quelle f\u00fcr den wasserdichten Sound-Bar. Die Musik wird \u00fcber Bluetooth an diesen Sound-Bar gesendet. Der Bluetooth Sound-Bar ist wasserdicht (IPX5), so dass er ideal f\u00fcr den Einsatz im Badezimmer ist. Mit dem mitgelieferten St\u00e4nder kann der Sound-Bar auf 4 verschiedene Arten positioniert werden. Sowohl stehend als auch an der Wand [&hellip;]","og_url":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/","og_site_name":"AquaSound","article_modified_time":"2022-09-29T09:55:01+00:00","og_image":[{"url":"https:\/\/aquasound.eu\/wp-content\/uploads\/SPKSB45-W-2.webp","width":1,"height":1,"type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/","url":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/","name":"SPKSB45-W Wasserdichten Sound-Bar","isPartOf":{"@id":"https:\/\/aquasound.eu\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/#primaryimage"},"image":{"@id":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/#primaryimage"},"thumbnailUrl":"https:\/\/aquasound.eu\/wp-content\/uploads\/SPKSB45-W-2.webp","datePublished":"2022-05-18T10:49:49+00:00","dateModified":"2022-09-29T09:55:01+00:00","breadcrumb":{"@id":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/#primaryimage","url":"https:\/\/aquasound.eu\/wp-content\/uploads\/SPKSB45-W-2.webp","contentUrl":"https:\/\/aquasound.eu\/wp-content\/uploads\/SPKSB45-W-2.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/aquasound.eu\/de\/produkt\/spksb45-w\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquasound.eu\/de\/"},{"@type":"ListItem","position":2,"name":"WooCommerce","item":"https:\/\/aquasound.eu\/nl\/woocommerce\/"},{"@type":"ListItem","position":3,"name":"SPKSB45-W Wasserdichten Sound-Bar"}]},{"@type":"WebSite","@id":"https:\/\/aquasound.eu\/nl\/#website","url":"https:\/\/aquasound.eu\/nl\/","name":"AquaSound","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquasound.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/aquasound.eu\/de\/wp-json\/wp\/v2\/product\/25658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquasound.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/aquasound.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquasound.eu\/de\/wp-json\/wp\/v2\/media\/24800"}],"wp:attachment":[{"href":"https:\/\/aquasound.eu\/de\/wp-json\/wp\/v2\/media?parent=25658"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/aquasound.eu\/de\/wp-json\/wp\/v2\/product_brand?post=25658"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/aquasound.eu\/de\/wp-json\/wp\/v2\/product_cat?post=25658"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/aquasound.eu\/de\/wp-json\/wp\/v2\/product_tag?post=25658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}